{"id":622,"date":"2023-07-06T10:42:09","date_gmt":"2023-07-06T09:42:09","guid":{"rendered":"https:\/\/www.drony.fr\/blog\/?p=622"},"modified":"2023-07-08T13:21:12","modified_gmt":"2023-07-08T12:21:12","slug":"nos-images-du-parcours-de-la-flamme-olympique-pour-le-departement-du-val-doise","status":"publish","type":"post","link":"https:\/\/www.drony.fr\/blog\/nos-images-du-parcours-de-la-flamme-olympique-pour-le-departement-du-val-doise\/","title":{"rendered":"Nos images du parcours de la Flamme Olympique pour le d\u00e9partement du Val d&rsquo;Oise"},"content":{"rendered":"\n<p>La flamme Olympique des \u00ab JO de Paris 2024 \u00bb <strong>passera en Val d&rsquo;Oise le 19 juillet 2024<\/strong>. Pour pr\u00e9senter le parcours, nous avons \u00e9t\u00e9 sollicit\u00e9 par le <a data-type=\"URL\" data-id=\"https:\/\/www.valdoise.fr\" href=\"https:\/\/www.valdoise.fr\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9partement du Val d&rsquo;Oise<\/a> pour fournir des vid\u00e9os par drone permettant d&rsquo;illustrer le parcours de la flamme. Le montage de la vid\u00e9o de pr\u00e9sentation \u00e9tant r\u00e9alis\u00e9 par le service communication du D\u00e9partement.<\/p>\n\n\n\n<p>Nous vous proposons un r\u00e9sum\u00e9 avec ce reportage photo. <strong>26 d\u00e9clarations et protocoles<\/strong> ont \u00e9t\u00e9 n\u00e9cessaires pour la r\u00e9alisation de cette mission. Entre la pr\u00e9paration administrative et le tournage, il aura fallu compter <strong>5 jours \u00e0 2 t\u00e9l\u00e9pilotes drone<\/strong> quand cela \u00e9tait n\u00e9cessaire, notamment <strong>pour les vols FPV<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #1 : Th\u00e9m\u00e9ricourt \u2014 Parc naturel r\u00e9gional du Vexin fran\u00e7ais<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Le ch\u00e2teau de Th\u00e9m\u00e9ricourt<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"624\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-1024x724.jpg\" alt=\"Le ch\u00e2teau et le parc de Th\u00e9m\u00e9ricourt dans le parc naturel r\u00e9gional du Vexin fran\u00e7ais - vue a\u00e9rienne par drone\" class=\"wp-image-624\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"626\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Le ch\u00e2teau et le parc de Th\u00e9m\u00e9ricourt dans le parc naturel r\u00e9gional du Vexin fran\u00e7ais - vue a\u00e9rienne par drone\" class=\"wp-image-626\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-parc-de-themericourt-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-chateau-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"625\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-chateau-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-1024x724.jpg\" alt=\"Le ch\u00e2teau et le parc de Th\u00e9m\u00e9ricourt dans le parc naturel r\u00e9gional du Vexin fran\u00e7ais - vue a\u00e9rienne par drone\" class=\"wp-image-625\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-chateau-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-chateau-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-chateau-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-chateau-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/01-chateau-de-themericourt-flamme-olympique-val-d-oise-drony-films240-01-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #2 : Auvers-sur-Oise &amp; M\u00e9ry-sur-Oise<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Le ch\u00e2teau, l&rsquo;auberge Ravoux, la mairie et l&rsquo;\u00e9glise Notre-Dame-de-l&rsquo;Assomption d\u2019Auvers-sur-Oise<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-chateau-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"634\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-chateau-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Le ch\u00e2teau d'Auvers-sur-Oise - vue a\u00e9rienne par drone\" class=\"wp-image-634\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-chateau-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-chateau-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-chateau-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-chateau-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-chateau-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-auberge-ravoux-flamme-olympique-val-d-oise-drony-films240-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"635\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-auberge-ravoux-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg\" alt=\"L'auberge RAVOUX d'Auvers-sur-Oise - vue a\u00e9rienne par drone\" class=\"wp-image-635\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-auberge-ravoux-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-auberge-ravoux-flamme-olympique-val-d-oise-drony-films240-1-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-auberge-ravoux-flamme-olympique-val-d-oise-drony-films240-1-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-auberge-ravoux-flamme-olympique-val-d-oise-drony-films240-1-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-auberge-ravoux-flamme-olympique-val-d-oise-drony-films240-1-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-mairie-flamme-olympique-val-d-oise-drony-films240-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"636\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-mairie-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg\" alt=\"La mairie d'Auvers-sur-Oise - vue a\u00e9rienne par drone\" class=\"wp-image-636\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-mairie-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-mairie-flamme-olympique-val-d-oise-drony-films240-1-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-mairie-flamme-olympique-val-d-oise-drony-films240-1-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-mairie-flamme-olympique-val-d-oise-drony-films240-1-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-mairie-flamme-olympique-val-d-oise-drony-films240-1-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-notre-dame-de-l-asomption-flamme-olympique-val-d-oise-drony-films240-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"637\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-notre-dame-de-l-asomption-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg\" alt=\"L'\u00e9glise Notre-Dame-de-l'Assomption d'Auvers-sur-Oise - vue a\u00e9rienne par drone\" class=\"wp-image-637\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-notre-dame-de-l-asomption-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-notre-dame-de-l-asomption-flamme-olympique-val-d-oise-drony-films240-1-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-notre-dame-de-l-asomption-flamme-olympique-val-d-oise-drony-films240-1-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-notre-dame-de-l-asomption-flamme-olympique-val-d-oise-drony-films240-1-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-notre-dame-de-l-asomption-flamme-olympique-val-d-oise-drony-films240-1-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-vue-ensemble-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"644\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-vue-ensemble-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Vue g\u00e9n\u00e9rale d'Auvers-sur-Oise depuis M\u00e9ry-sur-Oise - vue a\u00e9rienne par drone\" class=\"wp-image-644\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-vue-ensemble-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-vue-ensemble-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-vue-ensemble-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-vue-ensemble-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-auvers-sur-oise-vue-ensemble-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">La mairie et les bords de l\u2018Oise \u00e0 M\u00e9ry-sur-Oise<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mairie-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"643\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mairie-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg\" alt=\"La mairie de M\u00e9ry-sur-Oise - vue a\u00e9rienne par drone\" class=\"wp-image-643\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mairie-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-1-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mairie-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-1-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mairie-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-1-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mairie-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-1-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mairie-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-1-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"641\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Les bords de l'Oise \u00e0 M\u00e9ry-sur-Oise - vue a\u00e9rienne par drone\" class=\"wp-image-641\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/02-mery-sur-oise-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #3 : Pontoise &#8211; Cergy<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Quai de Pontoise, CY universit\u00e9 Site des Ch\u00eanes, H\u00f4tel du D\u00e9partement, Parc Fran\u00e7ois Mitterrand<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-pont-oise-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"651\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-pont-oise-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Quais de l'Oise \u00e0 Pontoise - vue a\u00e9rienne par drone\" class=\"wp-image-651\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-pont-oise-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-pont-oise-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-pont-oise-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-pont-oise-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-pont-oise-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"652\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Vue g\u00e9n\u00e9rale de Pontoise depuis les quais de l'Oise \u00e0 Pontoise - vue a\u00e9rienne par drone\" class=\"wp-image-652\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-pontoise-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-cy-paris-u-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"653\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-cy-paris-u-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"CY Cergy Paris Universit\u00e9 - vue a\u00e9rienne par drone\" class=\"wp-image-653\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-cy-paris-u-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-cy-paris-u-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-cy-paris-u-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-cy-paris-u-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-cy-paris-u-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"654\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Parc Fran\u00e7ois Mitterrand de Cergy - vue a\u00e9rienne par drone\" class=\"wp-image-654\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-hotel-du-departement-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"655\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-hotel-du-departement-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"H\u00f4tel du D\u00e9partement - vue a\u00e9rienne par drone\" class=\"wp-image-655\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-hotel-du-departement-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-hotel-du-departement-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-hotel-du-departement-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-hotel-du-departement-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/03-cergy-hotel-du-departement-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #4 : La for\u00eat de Montmorency<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">La for\u00eat de Montmorency &amp; le ch\u00e2teau de la Chasse \u2013 Saint-Prix<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-coureuse-footing-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"646\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-coureuse-footing-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Jeune femme courant sous les arbres de la for\u00eat de Montmorency - vue a\u00e9rienne par drone\" class=\"wp-image-646\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-coureuse-footing-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-coureuse-footing-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-coureuse-footing-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-coureuse-footing-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-coureuse-footing-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-arbres-footing-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"648\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-arbres-footing-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Les arbres de la for\u00eat de Montmorency - vue a\u00e9rienne par drone\" class=\"wp-image-648\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-arbres-footing-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-arbres-footing-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-arbres-footing-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-arbres-footing-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-arbres-footing-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-footing-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"647\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-footing-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Le ch\u00e2teau de la chasse \u00e0 Saint-Prix en for\u00eat de Montmorency - vue a\u00e9rienne par drone\" class=\"wp-image-647\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-footing-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-footing-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-footing-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-footing-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-footing-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"649\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Le ch\u00e2teau de la chasse \u00e0 Saint-Prix en for\u00eat de Montmorency - vue a\u00e9rienne par drone\" class=\"wp-image-649\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/04-foret-de-montmorency-chateau-de-la-chasse-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #5 : Sarcelles &amp; Garges-l\u00e8s-Gonesse<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Le parc du Fort de Stains, le centre sportif Nelson Mandela \u00e0 Sarcelles et le complexe sportif Pierre de Coubertin \u00e0 Garges-l\u00e8s-Gonesse<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-coureuse-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"661\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-coureuse-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Jeune femme qui court sur la piste d'athl\u00e9tisme du centre sportif Nelson Mandela \u00e0 Sarcelles - vue a\u00e9rienne par drone\" class=\"wp-image-661\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-coureuse-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-coureuse-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-coureuse-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-coureuse-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-coureuse-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"659\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Vue de la ville de Sarcelles depuis le centre sportif Nelson Mandela \u00e0 Sarcelles - vue a\u00e9rienne par drone\" class=\"wp-image-659\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"660\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Vue du parc du Fort de Stains depuis le complexe sportif Pierre de Coubertin \u00e0 Garges-l\u00e8s-Gonesse - vue a\u00e9rienne par drone\" class=\"wp-image-660\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-05-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"662\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg\" alt=\"Le complexe sportif Pierre de Coubertin \u00e0 Garges-l\u00e8s-Gonesse - vue a\u00e9rienne par drone\" class=\"wp-image-662\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-05-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-05-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-05-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-garges-les-gonesse-flamme-olympique-val-d-oise-drony-films240-05-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"658\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Vue topshot de la piste d'athl\u00e9tisme du centre sportif Nelson Mandela \u00e0 Sarcelles - vue a\u00e9rienne par drone\" class=\"wp-image-658\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/05-sarcelles-centre-sportif-nelson-mandela-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #6 : Cormeilles-en-Parisis, Argenteuil en passant par Sannois et Franconville<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Cormeilles-en-Parisis &amp; le parc Schlumberger<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-04-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"664\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg\" alt=\"La ville de Cormeilles-en-Parisis vue depuis le parc Schlumberger - Vue a\u00e9rienne par drone\" class=\"wp-image-664\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-04-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-04-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-04-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-04-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"666\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Topshot du parc Schlumberger \u00e0 Cormeilles-en-Parisis - Vue a\u00e9rienne par drone\" class=\"wp-image-666\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"665\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"L'aire de jeu du parc Schlumberger de la ville de Cormeilles-en-Parisis - Vue a\u00e9rienne par drone\" class=\"wp-image-665\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-05-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"667\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg\" alt=\"La ville de Cormeilles-en-Parisis vue depuis le parc Schlumberger - Vue a\u00e9rienne par drone\" class=\"wp-image-667\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-05-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-05-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-05-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-cormeiles-en-parisis-parc-schlumberger-la-flamme-olympique-val-d-oise-drony-films240-05-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Franconville et le parc Cadet de Vaux<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-04-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"668\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg\" alt=\"Topshot du parc Cadet de Vaux \u00e0 Franconville-la-Garenne - Vue a\u00e9rienne par drone\" class=\"wp-image-668\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-04-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-04-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-04-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-04-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-03-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"670\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-03-1024x724.jpg\" alt=\"Vue de Franconville depuis le parc Cadet de Vaux - Vue a\u00e9rienne par drone\" class=\"wp-image-670\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-03-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-03-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-03-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-03-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-03-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"669\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Topshot du parc Cadet de Vaux \u00e0 Franconville-la-Garenne - Vue a\u00e9rienne par drone\" class=\"wp-image-669\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-06-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"671\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-06-1024x724.jpg\" alt=\"Vue de Franconville depuis le parc Cadet de Vaux - Vue a\u00e9rienne par drone\" class=\"wp-image-671\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-06-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-06-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-06-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-06-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-franconville-parc-cadet-de-vaux-la-flamme-olympique-val-d-oise-drony-films240-06-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Sannois et le moulin<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"673\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Topshot du moulin de Sannois - Vue a\u00e9rienne par drone\" class=\"wp-image-673\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"672\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Moulin de Sannois - Vue a\u00e9rienne par drone\" class=\"wp-image-672\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-sannois-le-moulin-la-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Argenteuil, la basilique Saint-Denys &amp; le parc des berges<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-03-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"677\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-03-1024x724.jpg\" alt=\"Argenteuil et le parc des Berges - Vue a\u00e9rienne par drone\" class=\"wp-image-677\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-03-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-03-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-03-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-03-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-03-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-es-berges-la-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"676\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-es-berges-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Flow-park\/ Skatepark du parc des Berges \u00e0 Argenteuil - Vue a\u00e9rienne par drone\" class=\"wp-image-676\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-es-berges-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-es-berges-la-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-es-berges-la-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-es-berges-la-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-es-berges-la-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-basilique-la-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"681\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-basilique-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"la basilique Saint-Denys d'Argenteuil - Vue a\u00e9rienne par drone\" class=\"wp-image-681\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-basilique-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-basilique-la-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-basilique-la-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-basilique-la-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-basilique-la-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"675\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Argenteuil et le parc des Berges en topshot - Vue a\u00e9rienne par drone\" class=\"wp-image-675\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/06-argenteuil-parc-des-berges-la-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #7 : Deuil-la-Barre, Enghien-les-Bains, Saint-Gratien, Ermont et Eaubonne.<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Stade intercommunal de Deuil-la-Barre<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-04-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"678\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg\" alt=\"Joueuse de tennis au Stade intercommunal de Deuil-la-Barre - Vue a\u00e9rienne par drone\" class=\"wp-image-678\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-04-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-04-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-04-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-04-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-03-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"682\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-03-1024x724.jpg\" alt=\"Vue de Deuil-la-Barre depuis le stade intercommunal - Vue a\u00e9rienne par drone\" class=\"wp-image-682\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-03-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-03-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-03-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-03-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-03-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"680\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg\" alt=\"Topshot du stade intercommunal de Deuil-la-Barre - Vue a\u00e9rienne par drone\" class=\"wp-image-680\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-deuil-la-barre-la-flamme-olympique-val-d-oise-drony-films240-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Enghien-les-Bains, le lac, le casino Barri\u00e8re et le restaurant Fouquet&rsquo;s<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-12 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-05-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"683\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg\" alt=\"le lac d'Enghien-les-Bains - Vue a\u00e9rienne par drone\" class=\"wp-image-683\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-05-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-05-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-05-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-05-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-fouquets-la-flamme-olympique-val-d-oise-drony-films240-04-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"684\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-fouquets-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg\" alt=\"le lac, le casino Barri\u00e8re et le restaurant Fouquet's d'Enghien-les-Bains - Vue a\u00e9rienne par drone\" class=\"wp-image-684\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-fouquets-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-fouquets-la-flamme-olympique-val-d-oise-drony-films240-04-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-fouquets-la-flamme-olympique-val-d-oise-drony-films240-04-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-fouquets-la-flamme-olympique-val-d-oise-drony-films240-04-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-fouquets-la-flamme-olympique-val-d-oise-drony-films240-04-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-04-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"685\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg\" alt=\"Le casino Barri\u00e8re d'Enghien-les-Bains vue depuis le lac - Vue a\u00e9rienne par drone\" class=\"wp-image-685\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-04-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-04-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-04-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-04-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-enghien-les-bains-casino-la-flamme-olympique-val-d-oise-drony-films240-04-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Complexe sportif Raoul Dautry \u00e0 Ermont<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-13 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-05-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"690\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg\" alt=\"Complexe sportif Raoul Dautry \u00e0 Ermont - Vue a\u00e9rienne par drone\" class=\"wp-image-690\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-05-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-05-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-05-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-05-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"691\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"Complexe sportif Raoul Dautry \u00e0 Ermont - Vue a\u00e9rienne par drone\" class=\"wp-image-691\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-complexe-sportif-raoul-dautry-la-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ermont &amp; Eaubonne<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-14 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-eaubonne-la-flamme-olympique-val-d-oise-drony-films240-05-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"694\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-eaubonne-la-flamme-olympique-val-d-oise-drony-films240-05-1-1024x724.jpg\" alt=\"Vue de la gare de Ermont\/Eaubonne depuis le complexe sportif Raoul Dautry \u00e0 Ermont - Vue a\u00e9rienne par drone\" class=\"wp-image-694\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-eaubonne-la-flamme-olympique-val-d-oise-drony-films240-05-1-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-eaubonne-la-flamme-olympique-val-d-oise-drony-films240-05-1-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-eaubonne-la-flamme-olympique-val-d-oise-drony-films240-05-1-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-eaubonne-la-flamme-olympique-val-d-oise-drony-films240-05-1-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/07-ermont-eaubonne-la-flamme-olympique-val-d-oise-drony-films240-05-1-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tape #8 : Site de c\u00e9l\u00e9bration \u00e0 Soisy-sous-Montmorency (ville \u00e9tape)<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">hippodrome d\u2019Enghien-Soisy<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-15 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-05-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"686\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg\" alt=\"\" class=\"wp-image-686\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-05-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-05-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-05-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-05-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-05-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" data-id=\"687\" src=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg\" alt=\"\" class=\"wp-image-687\" srcset=\"https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-02-1024x724.jpg 1024w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-02-300x212.jpg 300w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-02-768x543.jpg 768w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-02-1536x1086.jpg 1536w, https:\/\/www.drony.fr\/blog\/wp-content\/uploads\/2023\/07\/08-enghien-soisy-hippodrome-la-flamme-olympique-val-d-oise-drony-films240-02-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Retrouvez le film mont\u00e9 par le service communication du D\u00e9partement du Val d&rsquo;Oise avec nos images<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Parcours du relais de la flamme olympique dans le Val d&#039;Oise\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/l7wCmnA654U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\">Besoin d&rsquo;une prestation audiovisuelle, une formation drone ou une remise \u00e0 niveau ?<\/h2>\n\n\n\n<p class=\"has-text-align-left\"><a href=\"https:\/\/www.drony.fr\/contact\/\" target=\"_blank\" rel=\"noreferrer noopener\">N&rsquo;h\u00e9sitez pas \u00e0 nous contacter sur la page de contact d\u00e9di\u00e9e \u00e0 votre demande<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La flamme Olympique des \u00ab JO de Paris 2024 \u00bb passera en Val d&rsquo;Oise le&#8230;<\/p>\n","protected":false},"author":2,"featured_media":725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,68,80],"tags":[82,83,84,81],"class_list":["post-622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-missions-drone","category-prestation-audiovisuelle","tag-flamme-olympique","tag-jeux-olympiques-paris-2024","tag-photos-par-drone","tag-val-doise"],"_links":{"self":[{"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/posts\/622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/comments?post=622"}],"version-history":[{"count":24,"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/posts\/622\/revisions"}],"predecessor-version":[{"id":751,"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/posts\/622\/revisions\/751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/media\/725"}],"wp:attachment":[{"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/media?parent=622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/categories?post=622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drony.fr\/blog\/wp-json\/wp\/v2\/tags?post=622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}